{"id":10717,"date":"2022-10-10T02:50:49","date_gmt":"2022-10-10T02:50:49","guid":{"rendered":"https:\/\/www.swisslearning.com\/?p=10717"},"modified":"2022-10-10T02:50:50","modified_gmt":"2022-10-10T02:50:50","slug":"aiglon-trips-programmes","status":"publish","type":"post","link":"https:\/\/www.swisslearning.com\/es\/news\/aiglon-trips-programmes\/","title":{"rendered":"Programas de viajes de Aiglon"},"content":{"rendered":"<p><strong>Los estudiantes de Aiglon disfrutan cada a\u00f1o de la oportunidad de realizar numerosos viajes fuera del campus, a veces esto puede ser parte de nuestro Programa B\u00e1sico, o puede ser una aventura especial a trav\u00e9s de nuestro Programa de Experiencia.<\/strong><\/p>\n<p>Si bien nuestra ubicaci\u00f3n alpina es hermosa, sabemos que parte de la educaci\u00f3n hol\u00edstica es aprender las lecciones que vienen con los viajes, ya sea el sentido de responsabilidad personal cuando te pones una mochila al hombro y te diriges a un nuevo lugar, el aprendizaje intercultural a medida que conoces gente muy diferente a ti, o la sensaci\u00f3n de asombro cuando te encuentras con lugares que solo hab\u00edas conocido a trav\u00e9s de fotos. Esta es la raz\u00f3n por la cual parte del viaje de cada aigloniano a trav\u00e9s de la escuela implica m\u00faltiples oportunidades para viajar.<\/p>\n<p>Muchos estudiantes de Aiglon ya son diversos y han viajado mucho. Como tal, tenemos la responsabilidad de brindarles a nuestros estudiantes un programa atractivo que no solo sea pertinente desde el punto de vista educativo, sino que est\u00e9 abierto a experiencias que no podr\u00edan obtener en ning\u00fan otro lugar. Por lo tanto, el programa de viajes de Aiglon se divide en dos componentes principales: nuestro programa b\u00e1sico y nuestro programa de experiencias.<\/p>\n<h2>Programa b\u00e1sico<\/h2>\n<p>Cada aigloniano tiene la oportunidad de viajar al menos una vez al a\u00f1o. Estas experiencias forman parte de nuestro programa central y est\u00e1n vinculadas a lo que sucede en el aula. Dos tipos de viajes son parte de nuestro programa principal, los costos de estos viajes son parte de las tasas escolares regulares.<\/p>\n<h6>Experiencia de aprendizaje cultural (CLE)<\/h6>\n<p>Un aspecto central del enfoque de Aiglon desde los primeros d\u00edas de la escuela, las Experiencias de aprendizaje cultural (CLE) son una oportunidad para que todos los estudiantes viajen durante el per\u00edodo de oto\u00f1o. Toda la escuela deja el campus para embarcarse en un grupo por a\u00f1o para explorar Suiza o para comprender el lugar de Suiza en el coraz\u00f3n de Europa. Estos viajes tienen un enfoque cultural que trabaja para unir lo que sucede en el sal\u00f3n de clases con experiencias del mundo real.<\/p>\n<p>Los estudiantes de Year 5 a 9 realizan experiencias suizas en Berna, Neuchatel, Z\u00farich y Lugano. Los estudiantes de Year 10 a 13 realizan experiencias europeas en Tur\u00edn, Lyon, Roma, Mil\u00e1n, Florencia, Venecia, Atenas y Budapest.<\/p>\n<h6>Viaje de descubrimiento de Aiglon (ADT)<\/h6>\n<p>Los Aiglon Discovery Trips (ADT) son una parte fundamental del Discovery Programme, nuestro plan de estudios personalizado desarrollado para los estudiantes de los a\u00f1os 7 a 9. Cada per\u00edodo de verano, los estudiantes de estos a\u00f1os se embarcan en un viaje de 10 d\u00edas lejos del campus para experimentar un nuevo parte del mundo y vincularse con el trabajo de clase que han estado haciendo durante todo el a\u00f1o. Estos viajes se enfocan en ofrecer nuevas experiencias en lugares \u00fanicos al mismo tiempo que crean oportunidades para la reflexi\u00f3n estructurada y el desarrollo personal.<\/p>\n<p>El Year 7 ADT visita la NASA en Huntsville, Alabama (EE. UU.), donde los estudiantes realizan un curso de dos semanas sobre supervivencia, entrenamiento de astronautas, ingenier\u00eda, vuelo espacial y xenobiolog\u00eda.<\/p>\n<p>El ADT de Year 8 visita Grecia con estudiantes que tienen una experiencia cultural e hist\u00f3rica de Atenas y sus alrededores antes de trasladarse a Corf\u00fa, donde los estudiantes reciben capacitaci\u00f3n RYA, intentando calificarse para tripular un yate de 15 m.<\/p>\n<p>El Year 9 ADT viaja al pueblo de Tiklik, Beng Maelea en Camboya. Aiglon tiene un proyecto de larga duraci\u00f3n que trabaja con el pueblo para promover una vida sostenible a trav\u00e9s de la educaci\u00f3n ecol\u00f3gica. Los estudiantes trabajan con los lugare\u00f1os para comprender los problemas, tanto locales como internacionales, antes de intentar encontrar soluciones.<\/p>\n<h2>Programa de experiencia<\/h2>\n<p>Durante m\u00e1s de 70 a\u00f1os, nuestra escuela se ha ganado una reputaci\u00f3n por nuestra perspectiva aventurera y la tradici\u00f3n de liderar expediciones desafiantes para estudiantes de todas las edades. Como tal, tambi\u00e9n podemos ofrecer experiencias de viaje adicionales que aprovechan nuestra gu\u00eda experta combinada con un ambicioso esp\u00edritu de aventura expedicionaria. Est\u00e1n dise\u00f1ados para empujar a los estudiantes en nuevas direcciones desafi\u00e1ndolos a comprender los principios de mente, cuerpo y esp\u00edritu de la escuela mientras se encuentran en una parte nueva e inexplorada del mundo.<\/p>\n<p>Los viajes que forman parte del Programa Experiencia se suman al Programa B\u00e1sico, aunque en ocasiones,\u00a0<em>los estudiantes pueden participar en uno de estos viajes en lugar de un viaje principal<\/em>. Tambi\u00e9n podr\u00e1n tener lugar parcialmente durante las vacaciones del trimestre. Estos viajes normalmente no forman parte de las tarifas escolares regulares. Los estudiantes deben solicitar estos viajes y ser aceptados.<\/p>\n<h6>Pr\u00f3ximos viajes del programa Experience<\/h6>\n<p>Ejemplos de viajes actuales o futuros del Programa de Experiencia incluyen Experiencia Cultural y Ecol\u00f3gica de Camboya, Experiencia Ecol\u00f3gica y de Aventura en el Mar Rojo, Experiencia Ecol\u00f3gica de Tailandia, Experiencia Ecol\u00f3gica de Honduras, Experiencia Cultural y Ecol\u00f3gica de Per\u00fa, Experiencia Cultural y de Aventura de Marruecos, Experiencia de Intercambio Cultural de Kenia y Tanzania, Islandia Viaje Cultural y Experiencia de Aventura, Italia Experiencia de Aventura.<\/p>\n<p>Entre el Programa B\u00e1sico y el Programa de Experiencia, cada aigloniano tiene la oportunidad de viajar por Suiza y Europa durante su tiempo en la escuela y acceder a una variedad de experiencias aventureras que creemos, como escuela, nos hacen una comunidad m\u00e1s fuerte y diversa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aiglon students enjoy the opportunity each year to take numerous trips away from campus, sometimes this might be part of our Core Programme, or it may be a special adventure through our Experience Programme. While our alpine location is beautiful, we know that part of holistic education is learning the lessons that come with travel [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10718,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-10717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aiglon Trips Programmes<\/title>\n<meta name=\"description\" content=\"Aiglon Trips Programmes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.swisslearning.com\/es\/news\/aiglon-trips-programmes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aiglon Trips Programmes\" \/>\n<meta property=\"og:description\" content=\"Aiglon Trips Programmes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.swisslearning.com\/es\/news\/aiglon-trips-programmes\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swisslearning\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-10T02:50:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T02:50:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2022\/10\/2022-OCT-Trips-Programme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isabelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/\"},\"author\":{\"name\":\"Isabelle\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"headline\":\"Aiglon Trips Programmes\",\"datePublished\":\"2022-10-10T02:50:49+00:00\",\"dateModified\":\"2022-10-10T02:50:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/\"},\"wordCount\":772,\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022-OCT-Trips-Programme.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/\",\"name\":\"Aiglon Trips Programmes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022-OCT-Trips-Programme.jpg\",\"datePublished\":\"2022-10-10T02:50:49+00:00\",\"dateModified\":\"2022-10-10T02:50:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"description\":\"Aiglon Trips Programmes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022-OCT-Trips-Programme.jpg\",\"contentUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022-OCT-Trips-Programme.jpg\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/aiglon-trips-programmes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.swisslearning.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aiglon Trips Programmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/\",\"name\":\"Swiss Learning\",\"description\":\"BOARDING SCHOOLS, HOTEL MANAGEMENT SCHOOLS AND CAMPS IN SWITZERLAND\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.swisslearning.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\",\"name\":\"Isabelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"caption\":\"Isabelle\"},\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/es\\\/author\\\/isabelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programas de viajes de Aiglon","description":"Programas de viajes de Aiglon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.swisslearning.com\/es\/news\/aiglon-trips-programmes\/","og_locale":"es_ES","og_type":"article","og_title":"Aiglon Trips Programmes","og_description":"Aiglon Trips Programmes","og_url":"https:\/\/www.swisslearning.com\/es\/news\/aiglon-trips-programmes\/","og_site_name":"Swiss Learning","article_publisher":"https:\/\/www.facebook.com\/swisslearning","article_published_time":"2022-10-10T02:50:49+00:00","article_modified_time":"2022-10-10T02:50:50+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2022\/10\/2022-OCT-Trips-Programme.jpg","type":"image\/jpeg"}],"author":"Isabelle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Isabelle","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/#article","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/"},"author":{"name":"Isabelle","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"headline":"Aiglon Trips Programmes","datePublished":"2022-10-10T02:50:49+00:00","dateModified":"2022-10-10T02:50:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/"},"wordCount":772,"image":{"@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2022\/10\/2022-OCT-Trips-Programme.jpg","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/","url":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/","name":"Programas de viajes de Aiglon","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/#primaryimage"},"image":{"@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2022\/10\/2022-OCT-Trips-Programme.jpg","datePublished":"2022-10-10T02:50:49+00:00","dateModified":"2022-10-10T02:50:50+00:00","author":{"@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"description":"Programas de viajes de Aiglon","breadcrumb":{"@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/#primaryimage","url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2022\/10\/2022-OCT-Trips-Programme.jpg","contentUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2022\/10\/2022-OCT-Trips-Programme.jpg","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/www.swisslearning.com\/news\/aiglon-trips-programmes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.swisslearning.com\/"},{"@type":"ListItem","position":2,"name":"Aiglon Trips Programmes"}]},{"@type":"WebSite","@id":"https:\/\/www.swisslearning.com\/#website","url":"https:\/\/www.swisslearning.com\/","name":"Aprendizaje suizo","description":"ESCUELAS INTERNAS, ESCUELAS DE GESTI\u00d3N DE HOTELES Y CAMPAMENTOS EN SUIZA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.swisslearning.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844","name":"Isabelle","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","caption":"Isabelle"},"url":"https:\/\/www.swisslearning.com\/es\/author\/isabelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/posts\/10717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/comments?post=10717"}],"version-history":[{"count":1,"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/posts\/10717\/revisions"}],"predecessor-version":[{"id":10719,"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/posts\/10717\/revisions\/10719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/media\/10718"}],"wp:attachment":[{"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/media?parent=10717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/categories?post=10717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.swisslearning.com\/es\/wp-json\/wp\/v2\/tags?post=10717"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}