{"id":12903,"date":"2025-09-30T08:53:44","date_gmt":"2025-09-30T08:53:44","guid":{"rendered":"https:\/\/www.swisslearning.com\/?p=12903"},"modified":"2025-10-13T08:55:55","modified_gmt":"2025-10-13T08:55:55","slug":"challenge-week-climbing-peaks-and-community-events","status":"publish","type":"post","link":"https:\/\/www.swisslearning.com\/it\/news\/challenge-week-climbing-peaks-and-community-events\/","title":{"rendered":"Settimana della sfida: scalate di vette ed eventi della comunit\u00e0"},"content":{"rendered":"<h1 class=\"wp-block-heading\"><\/h1>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757696768\/aiglonch\/l3hjdgehlbj2jyb6rzni\/AiglonChallengeWeek-3.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757697567\/aiglonch\/msggvrhxygmt1yqbrhcs\/AIGLON_SKYLINE_DENT_DU_MIDI-60Large.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757696768\/aiglonch\/dnocf2ppv4nqtgkfqqs1\/AiglonChallengeWeek-4.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757696768\/aiglonch\/zosjnjkw0nlwqdvzcxmp\/AiglonChallengeWeek-1.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757696768\/aiglonch\/wyxtwo6pswkbhcwdrk9f\/AiglonChallengeWeek-2.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757697309\/aiglonch\/gnc1qrzc9qwiw77hkaub\/AIGLON_BEAR_GRYLLS_DAY2-1Large.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757696768\/aiglonch\/bmda5in6a4slftxpetrt\/AiglonChallengeWeek-5.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757697217\/aiglonch\/vtxugbgwdaqnqumbyoa3\/AIGLON_BEAR_GRYLLS_DAY2-32Large.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/resources.finalsite.net\/images\/f_auto,q_auto,t_image_size_3\/v1757833830\/aiglonch\/ggfrcyftxmfum2zsz0mx\/AIGLON_ART_SOCIETY-18Large.jpg\" alt=\"studenti che eseguono musica classica nell&#039;Auditorium del Moghadam Campus Hub\"\/><\/figure>\n\n\n\n<p>12 settembre 2025<\/p>\n\n\n\n<p>Dalla conquista della maestosa cima del Dents du Midi agli eventi comunitari di The Gathering e Aiglon Beckwith Challenge, questa settimana ci siamo tutti sfidati a uscire dalla nostra zona di comfort.&nbsp;<\/p>\n\n\n\n<p>All&#039;inizio di ogni anno accademico, gli studenti partecipano alla &quot;Settimana della sfida&quot;, una delle settimane tematiche di Aiglon progettate per approfondire la nostra comprensione e abbracciare il nostro&nbsp;<a href=\"https:\/\/www.aiglon.ch\/about\/guiding-principles\" target=\"_blank\" rel=\"noreferrer noopener\">Principi guida<\/a>Attraverso eventi speciali e assemblee, la Challenge Week focalizza la nostra comunit\u00e0 sul potere trasformativo dell&#039;accettare le sfide, dando il tono a un inizio stimolante dell&#039;anno accademico.&nbsp;<\/p>\n\n\n\n<p>L&#039;Aiglon College \u00e8 stato fondato su un&#039;etica distintiva: lo sviluppo equilibrato di mente, corpo e spirito. Raggiungiamo questo obiettivo attraverso: sfida, rispetto, responsabilit\u00e0, diversit\u00e0 e servizio.&nbsp;<\/p>\n\n\n\n<p>Questa filosofia \u00e8 alla base di tutto ci\u00f2 che facciamo in Aiglon, sia dentro che fuori dall&#039;aula.<\/p>\n\n\n\n<p><strong>Dents du Midi: raggiungere nuove vette<\/strong><\/p>\n\n\n\n<p>Una delle prime cose che vi lascer\u00e0 senza fiato quando visitate Aiglon \u00e8 il panorama, che include il maestoso profilo del Dent du Midi. Svettante con i suoi 3.257 metri, \u00e8 parte integrante del paesaggio di Aiglon, cos\u00ec come lo \u00e8 all&#039;orizzonte dal campus. Tutte le generazioni di studenti di Aiglon conoscono il nome di questa montagna.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Il fulcro dell&#039;Aiglon Skyline Award \u00e8 quello di ispirare gli studenti a progredire verso la vetta. Scalare la montagna richiede resilienza, abilit\u00e0 e un lavoro di squadra collaborativo, per non parlare di un pizzico di fortuna nelle condizioni meteo.&nbsp;<\/p>\n\n\n\n<p>Lo scorso fine settimana, un gruppo di 13 studenti degli anni 11-13 ha intrapreso un impegnativo viaggio di due giorni&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=ciUMz07zk_s\">Spedizione Skyline High<\/a>Le spedizioni Skyline rappresentano le esperienze alpinistiche pi\u00f9 impegnative di Aiglon. Per alcuni, si \u00e8 trattato del secondo tentativo di raggiungere la cima dell&#039;Haute Cime, il punto pi\u00f9 alto. Le condizioni erano perfette, con sole splendente, cielo terso e una luna piena eclissata durante un&#039;eclissi lunare totale, la cosiddetta &quot;Luna di Sangue&quot;.&nbsp;<\/p>\n\n\n\n<p>La salita dura due giorni e gli studenti scalano fino a 12 ore su terreno tecnico. Hanno dormito all&#039;Auberge de Salanfe prima di partire all&#039;alba, alle 6 del mattino. Il terreno mutevole e i panorami spettacolari lungo il percorso. \u00c8 pi\u00f9 di una semplice scalata, \u00e8 un viaggio che incarna pienamente i Principi Guida di Aiglon.&nbsp;<\/p>\n\n\n\n<p>Con il supporto di guide locali esperte, gli studenti hanno raggiunto la vetta e hanno potuto scrutare la valle del Rodano per cercare di individuare il campus della scuola, una vista che non molti dei loro coetanei possono affermare di aver mai sperimentato prima.<\/p>\n\n\n\n<p><strong>Il raduno&nbsp;<\/strong><\/p>\n\n\n\n<p>L&#039;intera scuola si \u00e8 riunita all&#039;inizio dell&#039;anno accademico per &quot;The Gathering&quot;. Questo evento, una tradizione annuale di Aiglon dal 2022, prevede esibizioni studentesche che mettono in risalto lo spirito creativo e artistico di Aiglon, mentre un ex studente viene invitato a parlare, rafforzando cos\u00ec la tradizione della scuola.<\/p>\n\n\n\n<p>La nostra Direttrice Scolastica, Nicola Sparrow, ha pronunciato il discorso di apertura e di chiusura. Ci ha ricordato che questo \u00e8 uno dei rari momenti dell&#039;anno scolastico in cui siamo tutti riuniti e che facciamo parte di qualcosa di pi\u00f9 grande di noi. Il suo discorso si \u00e8 concentrato sul tema &quot;Sfida&quot;. &quot;La verit\u00e0 \u00e8 che non tutti vediamo le sfide che gli altri affrontano&quot;. Ha poi continuato: &quot;Le sfide sono sia visibili che invisibili. E per questo motivo, dobbiamo trattarci a vicenda con compassione e comprensione. Qui ad Aiglon, crediamo che le sfide non siano qualcosa da temere, ma da accogliere. \u00c8 attraverso le sfide che cresciamo: mentalmente, fisicamente, spiritualmente ed emotivamente. Ma la crescita non avviene da soli: siamo una comunit\u00e0, e far parte di una comunit\u00e0 significa non solo scalare la nostra montagna, ma anche aiutare gli altri a scalare la loro&quot;.&nbsp;<\/p>\n\n\n\n<p>Gli School Guardians hanno presentato l&#039;evento e condiviso alcune delle loro recenti sfide, dalla scalata del Dents du Midi dello scorso fine settimana all&#039;adattamento alla routine post-estiva delle sveglie quotidiane alle 7 del mattino.&nbsp;<\/p>\n\n\n\n<p>Simon Kidston (Alpina, 1985, ex allievo di Aiglon, commerciante di auto d&#039;epoca, collezionista, commentatore e imprenditore britannico) ha tenuto il discorso principale. Ha concluso il suo intervento affermando: &quot;Se c&#039;\u00e8 un pensiero che posso lasciare a voi, alcuni dei talenti pi\u00f9 brillanti al mondo, se siete abbastanza fortunati da essere in Aiglon, \u00e8 questo: scegliete qualcosa che vi appassiona e fatelo al meglio delle vostre capacit\u00e0. Non preoccupatevi se non sapete ancora cosa sia, a volte basta vivere un po&#039; di pi\u00f9 per scoprirlo. Ho detto ai miei figli, che ora hanno vent&#039;anni, che se amate qualcosa vi impegnerete duramente, se vi impegnerete duramente diventerete bravi e se sarete i migliori in qualche modo ne ricaverete il sostentamento&quot;.&nbsp;<\/p>\n\n\n\n<p>Uno dei momenti salienti del programma \u00e8 stato il canto con l&#039;intera comunit\u00e0 scolastica, con interpretazioni entusiasmanti di Lean on Me (Bill Withers) e Wake Me Up (Avicii).<\/p>\n\n\n\n<p><strong>Bear Grylls: &quot;Non mollare mai&quot;&nbsp;<\/strong><\/p>\n\n\n\n<p>L&#039;avventuriero ed esploratore Bear Grylls e il suo team della Bear Grylls Survival Academy sono tornati al campus per condividere esperienze di vita e consigli di sopravvivenza.&nbsp;<\/p>\n\n\n\n<p>Il primo giorno di visita, gli studenti dal terzo all&#039;undicesimo anno si sono diretti all&#039;Auditorium del Moghadam Campus Hub per immergersi nello spettacolo &quot;Never Give Up&quot;. \u00c8 stato un pomeriggio indimenticabile di storie, sopravvivenza e ispirazione: uno spettacolo dal vivo divertente, emozionante e adatto alle famiglie, per avventurieri di tutte le et\u00e0. Bear ha condiviso la sua vita pi\u00f9 incredibile: dalla conduzione di serie TV di successo come You vs. Wild, Man vs. Wild e Running Wild, alla condivisione di consigli di sopravvivenza con alcune delle figure pi\u00f9 riconoscibili al mondo, tra cui Barack Obama nella natura selvaggia dell&#039;Alaska, abbiamo ascoltato storie avvincenti e immagini straordinarie delle sue pi\u00f9 grandi avventure. Oltre a commoventi racconti di perseveranza, coraggio e gentilezza, tra cui la sua drammatica ripresa da un incidente di paracadutismo quasi fatale e le sfide che ha dovuto affrontare nella natura selvaggia.<\/p>\n\n\n\n<p>Al termine dello spettacolo, due studenti delle scuole elementari hanno ricevuto il &quot;Premio Eroe Sconosciuto&quot;. Questo prestigioso riconoscimento premia e celebra i giovani che hanno dimostrato coraggio, gentilezza e resilienza eccezionali, o che si sono distinti per il loro impegno nella comunit\u00e0.<\/p>\n\n\n\n<p>La mattina seguente, dopo i tradizionali due minuti di silenzio, Bear Grylls ha guidato la meditazione mattutina nell&#039;Auditorium. &quot;La vita a qualsiasi et\u00e0 pu\u00f2 essere un ottovolante&quot;, ha esordito. &quot;Un giorno sei in cima, al settimo cielo, tutto va per il verso giusto. E poi il giorno dopo ti senti come se stessi lottando contro tutto. Hai stress, dubbi, ti senti perso, forse a volte un po&#039; terrorizzato. Ma va bene cos\u00ec. La vita \u00e8 una giungla, ed \u00e8 progettata per essere spaventosa, ma la vita \u00e8 anche una questione di apparizione&quot;. Durante i 5 minuti del suo discorso, ha offerto spunti stimolanti sui &quot;poteri segreti dentro di noi&quot; e sul fatto che &quot;le tempeste passano sempre&quot;. Per concludere, ha affermato: &quot;Le persone pi\u00f9 forti non sono quelle che non lottano mai, sono quelle che continuano ad andare avanti quando fa pi\u00f9 male. Quindi restate sulla rotta. Occhi puntati sul premio e non arrendetevi mai&quot;.&nbsp;<\/p>\n\n\n\n<p>Nel febbraio 2024, Aiglon ha annunciato la partnership con&nbsp;<a href=\"https:\/\/www.aiglon.ch\/community\/news\/news\/~board\/public-news\/post\/aiglon-partners-bear-grylls\">Accademia di sopravvivenza di Bear Grylls&nbsp;<\/a>(BGSA) per creare un programma di educazione all&#039;aria aperta basato sui valori, ricco di avventure e sfide: Aiglon Mountain School. Quest&#039;estate abbiamo anche ospitato il primo programma &quot;Avventura&quot; presso l&#039;Aiglon Summer Camp, in collaborazione con il team di BGSA.<\/p>\n\n\n\n<p><strong>La sfida di Aiglon Beckwith: il viaggio \u00e8 importante quanto la destinazione&nbsp;<\/strong><\/p>\n\n\n\n<p>Il&nbsp;<a href=\"https:\/\/youtu.be\/sW7HRnBd3Co\" target=\"_blank\" rel=\"noreferrer noopener\">Sfida Aiglon Beckwith<\/a>&nbsp;\u00e8 parte integrante della &quot;Settimana della sfida&quot;. \u00c8 una tradizione di lunga data che riunisce tutti gli studenti e il personale e contribuisce a segnare l&#039;inizio dell&#039;anno accademico.<\/p>\n\n\n\n<p>Quattrocentootto studenti delle scuole elementari e medie, insieme al personale, hanno partecipato a questo evento che ha coinvolto l&#039;intera comunit\u00e0. Il percorso per gli studenti dell&#039;ultimo anno \u00e8 di circa 6 km con un dislivello di 650 m. Gli studenti delle classi terza e quarta elementare sono partiti da Les Bouquetins, mentre gli studenti delle classi quinta, quinta e ottava sono partiti dal Col du Soud. Poi hanno concluso il percorso insieme al resto degli studenti dell&#039;ultimo anno al Col de Bretaye.&nbsp;<\/p>\n\n\n\n<p>Le condizioni meteorologiche erano ideali: cielo leggermente coperto, ma niente pioggia e di tanto in tanto spuntavano i raggi del sole tra le nuvole.&nbsp;<\/p>\n\n\n\n<p>In quella che spesso viene semplicemente chiamata &quot;La Sfida&quot;, questa rimane una tradizione consolidata in cui studenti e personale si uniscono per fare escursioni o correre sui sentieri montani locali, culminando con il traguardo a Bretaye, un luogo che incarna il nostro ambiente montano. Sebbene la Sfida sia spesso vista come una prova fisica, \u00e8 molto pi\u00f9 di questo: \u00e8 una celebrazione della comunit\u00e0, della perseveranza e dello spirito di Aiglon.<\/p>\n\n\n\n<p>I primi studenti a tagliare il traguardo erano quelli delle classi terza e quarta. Accompagnati dai loro insegnanti, camminando o correndo, si sono concentrati sul raggiungimento del traguardo con sorrisi e cameratismo.&nbsp;<\/p>\n\n\n\n<p>Il primo posto \u00e8 andato a uno studente dell&#039;ultimo anno di scuola superiore, in rappresentanza del Delaware. Ha completato il percorso in 40 minuti e 01 secondi. \u00c8 la prima volta che uno studente dell&#039;anno 10 vince la Challenge. \u00c8 stato seguito da vicino da un ragazzo dell&#039;Alpina e al terzo posto da una ragazza dell&#039;anno 10 in rappresentanza di Clairmont. Il suo tempo \u00e8 stato di 36 secondi inferiore al primo, il secondo pi\u00f9 veloce tra le ragazze dai tempi dei record dell&#039;Aiglon negli ultimi quattro anni.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Il momento migliore dell&#039;Aiglon Beckwith Challenge per James Dyson (Responsabile di Educazione Fisica e Sport) \u00e8 stato: &quot;Quando la nostra studentessa sudanese ha completato il percorso in 2 ore e 30 minuti. Ci siamo offerti di prendere il treno per scendere, ma lei era determinata a tagliare il traguardo. Ha continuato fino a completare il percorso. \u00c8 la distanza pi\u00f9 lunga che abbia mai percorso correndo o camminando, e alla massima altitudine. \u00c8 stato un risultato epico!&quot;.&nbsp;<\/p>\n\n\n\n<p>L&#039;unica pensione ad aver visto tutti gli studenti completare il corso \u00e8 Le Trient. Con oltre 30 studenti dal 10\u00b0 al 13\u00b0 anno, questo \u00e8 un risultato di cui essere orgogliosi.&nbsp;<\/p>\n\n\n\n<p>La parte pi\u00f9 importante di questo evento \u00e8 la partecipazione. Congratulazioni a tutti gli studenti e al personale che hanno partecipato. \u00c8 stato un momento fondamentale per iniziare l&#039;anno.&nbsp;<\/p>\n\n\n\n<p><strong>Societ\u00e0 delle Arti Aiglon&nbsp;<\/strong><\/p>\n\n\n\n<p>E per concludere la settimana, Aiglon ospita l&#039;inaugurazione&nbsp;<a href=\"https:\/\/www.aiglon.ch\/community\/aiglon-society-of-the-arts\">Societ\u00e0 delle Arti Aiglon<\/a>&nbsp;Evento. Sette studenti di musica di grande talento hanno provato con 37 musicisti della Chambre d&#039;Orchestre de Gen\u00e8ve per un&#039;esibizione indimenticabile. In vista dell&#039;esibizione, che si terr\u00e0 sabato 13 settembre, questi studenti hanno abbandonato la loro comfort zone per suonare con questa prestigiosa orchestra, guidata dal direttore artistico e direttore d&#039;orchestra Rapha\u00ebl Merlin, e con il violinista di fama mondiale Svetlin Roussev. Gli studenti hanno ascoltato i consigli degli esperti musicisti e si sono fatti mentori a vicenda lungo il percorso. Questa \u00e8 un&#039;esperienza e una sfida che rimarr\u00e0 impressa nella memoria per tutta la vita.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>12&nbsp;September,&nbsp;2025 From summiting the majestic Dents du Midi, to the community events of The Gathering and the Aiglon Beckwith Challenge, this week we have all challenged ourselves to step out of our comfort zone.&nbsp; At the beginning of each academic year, students participate in \u2018Challenge Week\u2019, one of Aiglon&#8217;s thematic focus weeks designed to deepen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12904,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-12903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alumni Highlight the Power of Lifelong Connections<\/title>\n<meta name=\"description\" content=\"Alumni Highlight the Power of Lifelong Connections\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.swisslearning.com\/it\/news\/challenge-week-climbing-peaks-and-community-events\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alumni Highlight the Power of Lifelong Connections\" \/>\n<meta property=\"og:description\" content=\"Alumni Highlight the Power of Lifelong Connections\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.swisslearning.com\/it\/news\/challenge-week-climbing-peaks-and-community-events\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swisslearning\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T08:53:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T08:55:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/10\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Isabelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/\"},\"author\":{\"name\":\"Isabelle\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"headline\":\"Challenge Week: Climbing Peaks and Community Events\",\"datePublished\":\"2025-09-30T08:53:44+00:00\",\"dateModified\":\"2025-10-13T08:55:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/\"},\"wordCount\":1790,\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/\",\"name\":\"Alumni Highlight the Power of Lifelong Connections\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp\",\"datePublished\":\"2025-09-30T08:53:44+00:00\",\"dateModified\":\"2025-10-13T08:55:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"description\":\"Alumni Highlight the Power of Lifelong Connections\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp\",\"contentUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/challenge-week-climbing-peaks-and-community-events\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.swisslearning.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Challenge Week: Climbing Peaks and Community Events\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/\",\"name\":\"Swiss Learning\",\"description\":\"BOARDING SCHOOLS, HOTEL MANAGEMENT SCHOOLS AND CAMPS IN SWITZERLAND\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.swisslearning.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\",\"name\":\"Isabelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"caption\":\"Isabelle\"},\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/it\\\/author\\\/isabelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli ex studenti sottolineano il potere delle connessioni durature","description":"Gli ex studenti sottolineano il potere delle connessioni durature","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.swisslearning.com\/it\/news\/challenge-week-climbing-peaks-and-community-events\/","og_locale":"it_IT","og_type":"article","og_title":"Alumni Highlight the Power of Lifelong Connections","og_description":"Alumni Highlight the Power of Lifelong Connections","og_url":"https:\/\/www.swisslearning.com\/it\/news\/challenge-week-climbing-peaks-and-community-events\/","og_site_name":"Swiss Learning","article_publisher":"https:\/\/www.facebook.com\/swisslearning","article_published_time":"2025-09-30T08:53:44+00:00","article_modified_time":"2025-10-13T08:55:55+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/10\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp","type":"image\/webp"}],"author":"Isabelle","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Isabelle","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/#article","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/"},"author":{"name":"Isabelle","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"headline":"Challenge Week: Climbing Peaks and Community Events","datePublished":"2025-09-30T08:53:44+00:00","dateModified":"2025-10-13T08:55:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/"},"wordCount":1790,"image":{"@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/10\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/","url":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/","name":"Gli ex studenti sottolineano il potere delle connessioni durature","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/#primaryimage"},"image":{"@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/10\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp","datePublished":"2025-09-30T08:53:44+00:00","dateModified":"2025-10-13T08:55:55+00:00","author":{"@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"description":"Gli ex studenti sottolineano il potere delle connessioni durature","breadcrumb":{"@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/#primaryimage","url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/10\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp","contentUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/10\/AIGLON_SKYLINE_DENT_DU_MIDI-109Large.webp","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.swisslearning.com\/news\/challenge-week-climbing-peaks-and-community-events\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.swisslearning.com\/"},{"@type":"ListItem","position":2,"name":"Challenge Week: Climbing Peaks and Community Events"}]},{"@type":"WebSite","@id":"https:\/\/www.swisslearning.com\/#website","url":"https:\/\/www.swisslearning.com\/","name":"Apprendimento svizzero","description":"CONVITI, SCUOLE DI GESTIONE ALBERGHIERA E CAMPEGGI IN SVIZZERA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.swisslearning.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844","name":"Isabelle","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","caption":"Isabelle"},"url":"https:\/\/www.swisslearning.com\/it\/author\/isabelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/posts\/12903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/comments?post=12903"}],"version-history":[{"count":1,"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/posts\/12903\/revisions"}],"predecessor-version":[{"id":12905,"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/posts\/12903\/revisions\/12905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/media\/12904"}],"wp:attachment":[{"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/media?parent=12903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/categories?post=12903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.swisslearning.com\/it\/wp-json\/wp\/v2\/tags?post=12903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}