{"id":12302,"date":"2024-10-08T02:27:25","date_gmt":"2024-10-08T02:27:25","guid":{"rendered":"https:\/\/www.swisslearning.com\/?p=12302"},"modified":"2024-10-08T02:27:27","modified_gmt":"2024-10-08T02:27:27","slug":"how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine","status":"publish","type":"post","link":"https:\/\/www.swisslearning.com\/pt\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/","title":{"rendered":"Como um novo curso de empreendedorismo est\u00e1 ajudando os alunos da Aiglon a brilhar"},"content":{"rendered":"<h2 class=\"wp-block-heading\" id=\"h-stanislas-helou\"><\/h2>\n\n\n\n<p>Os pais esperam que as escolas equipem seus filhos com o conhecimento, as habilidades e as capacidades de pensamento cr\u00edtico necess\u00e1rias para prosperar no mundo real. Mas, com muita frequ\u00eancia, esse n\u00e3o \u00e9 o caso. Por exemplo, no Reino Unido, uma&nbsp;<a href=\"https:\/\/www.thetimes.com\/uk\/education\/article\/does-school-prepare-children-for-work-only-a-fifth-of-voters-think-so-cjjgzjj69\">pesquisa recente<\/a>&nbsp;descobriram que mais de 70% dos pais disseram que o sistema educacional d\u00e1 pouca \u00eanfase \u00e0 prepara\u00e7\u00e3o dos jovens para o trabalho e 84% disseram que n\u00e3o se concentra o suficiente nas habilidades para a vida.<\/p>\n\n\n\n<p>Ent\u00e3o, como os educadores podem preparar melhor os alunos para n\u00e3o apenas terem um bom desempenho acad\u00eamico, mas tamb\u00e9m prosperarem profissional e pessoalmente depois de se formarem?<\/p>\n\n\n\n<p>Isso \u00e9 algo que os professores do Aiglon College, Jack George, Assistant Head, Discovery, Ann-Marie Thomson, Head of Enterprise, e Darren Wise, Director of IT, t\u00eam pensado muito. \u201cPor muitos anos, o Sr. Wise e eu temos falado sobre como achamos que as escolas precisar\u00e3o se voltar mais para o aprendizado baseado em projetos e orientado por investiga\u00e7\u00e3o, se quiserem ajudar os alunos a adquirir as habilidades e compet\u00eancias necess\u00e1rias para o futuro mundo do trabalho\u201d, diz o Sr. George.<\/p>\n\n\n\n<p>Este ano, com a introdu\u00e7\u00e3o de um curso baseado em projetos para&nbsp;<a href=\"https:\/\/www.aiglon.ch\/learning\/discovery-years\" target=\"_blank\" rel=\"noreferrer noopener\">Ano 9<\/a>&nbsp;estudantes focados em empreendedorismo e intraempreendedorismo, o Sr. George, a Sra. Thomson e o Sr. Wise est\u00e3o colocando esses pensamentos em pr\u00e1tica. O curso \u2014 chamado&nbsp;<em>Fus\u00e3o Empresarial&nbsp;<\/em>\u2014 abrange muitos conceitos relevantes de neg\u00f3cios e startups, e ver\u00e1 os alunos desenvolverem seus pr\u00f3prios produtos ou servi\u00e7os e seguirem os passos para levar suas ideias ao mercado. \u201cIsso dar\u00e1 aos alunos a chance de aprender sobre conceitos de neg\u00f3cios como design thinking, pesquisa de mercado, planejamento financeiro, prototipagem, mas ent\u00e3o eles tamb\u00e9m aplicar\u00e3o o que est\u00e3o aprendendo enquanto trabalham em seus projetos estendidos\u201d, explica o Sr. Wise.<\/p>\n\n\n\n<p>O curso tamb\u00e9m complementar\u00e1 parte do trabalho que acontece em outras aulas, como computa\u00e7\u00e3o, e permitir\u00e1 que os alunos aprofundem seus conhecimentos aplicando o que aprenderam em situa\u00e7\u00f5es pr\u00e1ticas. \u201cO curso oferece aos alunos a oportunidade de ganhar habilidades t\u00e9cnicas em \u00e1reas como design de jogos, web design, design de aplicativos, prototipagem r\u00e1pida, impress\u00e3o\/cria\u00e7\u00e3o 3D e CAD\/CAM, \u00e0 medida que ganham habilidades capazes de criar seus produtos\u201d, diz o Sr. Wise.<\/p>\n\n\n\n<p>Para dar in\u00edcio ao processo, os alunos do curso participaram recentemente de uma&nbsp;<em>Dia de Start-Up<\/em>&nbsp;\u2014 uma oportunidade para eles obterem uma vis\u00e3o geral de alguns dos conceitos que aprender\u00e3o. \u201cFoi quase como um trailer de filme para o curso inteiro\u201d, diz o Sr. George sobre o evento. \u201cEles puderam mergulhar em muitas coisas diferentes, ent\u00e3o eles t\u00eam uma ideia b\u00e1sica da hist\u00f3ria, mas agora, nas pr\u00f3ximas semanas e meses, eles ir\u00e3o mais fundo e entrar\u00e3o nos detalhes.\u201d<\/p>\n\n\n\n<p>No in\u00edcio do evento, os alunos foram convidados a pensar em ideias de startups para a casa. Eles ent\u00e3o tiveram que fazer workshops com a orienta\u00e7\u00e3o de oito especialistas: quatro ex-alunos da Aiglon que montaram e escalaram seus pr\u00f3prios neg\u00f3cios com sucesso e quatro membros do&nbsp;<a href=\"https:\/\/arttechfoundation.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Funda\u00e7\u00e3o Art Tech<\/a>, uma rede su\u00ed\u00e7a de empreendedores. \u201cFoi fascinante observar os empreendedores encorajando os alunos a decompor suas grandes ideias e os empurrando a pensar nos detalhes, como uma pequena falha de design que poderia levar a um fracasso muito maior\u201d, diz Ann-Marie Thomson. \u201cNo in\u00edcio, os alunos ficaram um pouco surpresos, com alguns sentindo que seu trabalho estava sendo criticado, mas eles rapidamente perceberam que, na verdade, os empreendedores realmente amavam suas ideias, eles estavam apenas tentando faz\u00ea-los pensar sobre elas mais profundamente.\u201d<\/p>\n\n\n\n<p>S\u00e3o esses tipos de habilidades \u2014 identificar um problema, encontrar uma solu\u00e7\u00e3o para ele, iterar e ent\u00e3o ser capaz de implement\u00e1-la \u2014 que s\u00e3o t\u00e3o procuradas no mundo do trabalho. E s\u00e3o esses tipos de habilidades que o Sr. Wise acha que os alunos desenvolver\u00e3o ao longo do curso. \u201cMuitos cursos envolvem alunos sendo conduzidos por um caminho, ent\u00e3o seu aprendizado \u00e9 muito direcionado e ditado\u201d, diz o Sr. Wise. \u201cNa verdade, quando voc\u00ea d\u00e1 a eles um peda\u00e7o de papel em branco e os equipa com as habilidades certas, eles podem encontrar seu pr\u00f3prio caminho.\u201d<\/p>\n\n\n\n<p>Essa abordagem complementa a filosofia educacional mais ampla da Aiglon, acredita o Sr. George. \u201cA educa\u00e7\u00e3o tradicional pressup\u00f5e progress\u00e3o linear; a Aiglon \u00e9 uma escola de desenvolvimento, e oferecemos uma maneira personalizada para os alunos escreverem sua pr\u00f3pria hist\u00f3ria.\u201d<\/p>\n\n\n\n<p>Se os resultados de&nbsp;<em>Dia de Start-Up<\/em>&nbsp;s\u00e3o algo para seguir, os alunos conseguiram escrever algumas hist\u00f3rias muito interessantes at\u00e9 o final deste curso. \u201cTodos no evento ficaram surpresos com o que um grupo de jovens de 13 anos conseguiu realizar em um dia\u201d, diz o Sr. Wise. \u201cEles foram de praticamente zero no in\u00edcio do dia para ter uma apresenta\u00e7\u00e3o finalizada para mostrar ao p\u00fablico. Alguns dos empreendedores disseram que o que os alunos apresentaram n\u00e3o estava muito longe do que eles viram no mundo real, com projetos reais.\u201d<\/p>\n\n\n\n<p>N\u00e3o foram apenas os empreendedores que sa\u00edram otimistas sobre o que os alunos poderiam alcan\u00e7ar.<em>Dia de Start-Up<\/em>&nbsp;foi como uma grande e emocionante aventura no mundo dos neg\u00f3cios, e me mostrou o qu\u00e3o divertido e legal pode ser ter novas ideias e faz\u00ea-las acontecer\u201d, diz Yuina, uma das alunas que participou do evento. \u201cIsso me fez sentir mais confiante, como se eu pudesse realmente tentar come\u00e7ar meu pr\u00f3prio neg\u00f3cio um dia e talvez at\u00e9 fazer algo incr\u00edvel!\u201d<\/p>","protected":false},"excerpt":{"rendered":"<p>Parents hope that schools will equip their children with the knowledge, skills and critical thinking abilities needed to thrive in the real world. But all too often that isn\u2019t the case. For example, in the UK, a&nbsp;recent survey&nbsp;found that over 70% of parents said the education system puts too little emphasis on preparing young people [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12303,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-12302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How a new entrepreneurship course is helping Aiglon students shine<\/title>\n<meta name=\"description\" content=\"How a new entrepreneurship course is helping Aiglon students shine\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.swisslearning.com\/pt\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How a new entrepreneurship course is helping Aiglon students shine\" \/>\n<meta property=\"og:description\" content=\"How a new entrepreneurship course is helping Aiglon students shine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.swisslearning.com\/pt\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swisslearning\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T02:27:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-08T02:27:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2024\/10\/StartUpDay2024_7.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Isabelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/\"},\"author\":{\"name\":\"Isabelle\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"headline\":\"How a new entrepreneurship course is helping Aiglon students shine\",\"datePublished\":\"2024-10-08T02:27:25+00:00\",\"dateModified\":\"2024-10-08T02:27:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/\"},\"wordCount\":896,\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/StartUpDay2024_7.webp\",\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/\",\"name\":\"How a new entrepreneurship course is helping Aiglon students shine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/StartUpDay2024_7.webp\",\"datePublished\":\"2024-10-08T02:27:25+00:00\",\"dateModified\":\"2024-10-08T02:27:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"description\":\"How a new entrepreneurship course is helping Aiglon students shine\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/StartUpDay2024_7.webp\",\"contentUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/StartUpDay2024_7.webp\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.swisslearning.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How a new entrepreneurship course is helping Aiglon students shine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/\",\"name\":\"Swiss Learning\",\"description\":\"BOARDING SCHOOLS, HOTEL MANAGEMENT SCHOOLS AND CAMPS IN SWITZERLAND\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.swisslearning.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\",\"name\":\"Isabelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"caption\":\"Isabelle\"},\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/pt\\\/author\\\/isabelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como um novo curso de empreendedorismo est\u00e1 ajudando os alunos da Aiglon a brilhar","description":"Como um novo curso de empreendedorismo est\u00e1 ajudando os alunos da Aiglon a brilhar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.swisslearning.com\/pt\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/","og_locale":"pt_BR","og_type":"article","og_title":"How a new entrepreneurship course is helping Aiglon students shine","og_description":"How a new entrepreneurship course is helping Aiglon students shine","og_url":"https:\/\/www.swisslearning.com\/pt\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/","og_site_name":"Swiss Learning","article_publisher":"https:\/\/www.facebook.com\/swisslearning","article_published_time":"2024-10-08T02:27:25+00:00","article_modified_time":"2024-10-08T02:27:27+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2024\/10\/StartUpDay2024_7.webp","type":"image\/webp"}],"author":"Isabelle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Isabelle","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/#article","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/"},"author":{"name":"Isabelle","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"headline":"How a new entrepreneurship course is helping Aiglon students shine","datePublished":"2024-10-08T02:27:25+00:00","dateModified":"2024-10-08T02:27:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/"},"wordCount":896,"image":{"@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2024\/10\/StartUpDay2024_7.webp","articleSection":["News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/","url":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/","name":"Como um novo curso de empreendedorismo est\u00e1 ajudando os alunos da Aiglon a brilhar","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/#primaryimage"},"image":{"@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2024\/10\/StartUpDay2024_7.webp","datePublished":"2024-10-08T02:27:25+00:00","dateModified":"2024-10-08T02:27:27+00:00","author":{"@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"description":"Como um novo curso de empreendedorismo est\u00e1 ajudando os alunos da Aiglon a brilhar","breadcrumb":{"@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/#primaryimage","url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2024\/10\/StartUpDay2024_7.webp","contentUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2024\/10\/StartUpDay2024_7.webp","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.swisslearning.com\/news\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.swisslearning.com\/"},{"@type":"ListItem","position":2,"name":"How a new entrepreneurship course is helping Aiglon students shine"}]},{"@type":"WebSite","@id":"https:\/\/www.swisslearning.com\/#website","url":"https:\/\/www.swisslearning.com\/","name":"Swiss Learning","description":"ESCOLAS DE EMBARQUE, ESCOLAS DE GEST\u00c3O DE HOTELARIA E CAMPS NA SU\u00cd\u00c7A","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.swisslearning.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844","name":"Isabelle","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","caption":"Isabelle"},"url":"https:\/\/www.swisslearning.com\/pt\/author\/isabelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts\/12302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/comments?post=12302"}],"version-history":[{"count":1,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts\/12302\/revisions"}],"predecessor-version":[{"id":12304,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts\/12302\/revisions\/12304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/media\/12303"}],"wp:attachment":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/media?parent=12302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/categories?post=12302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/tags?post=12302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}