{"id":12851,"date":"2025-08-18T05:56:03","date_gmt":"2025-08-18T05:56:03","guid":{"rendered":"https:\/\/www.swisslearning.com\/?p=12851"},"modified":"2025-08-18T05:59:01","modified_gmt":"2025-08-18T05:59:01","slug":"preparing-students-for-tomorrow-and-a-world-in-constant-change","status":"publish","type":"post","link":"https:\/\/www.swisslearning.com\/pt\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/","title":{"rendered":"Preparando os alunos para o amanh\u00e3 e um mundo em constante mudan\u00e7a"},"content":{"rendered":"<p>Quando John Corlette fundou o Aiglon College em 1949, as coisas eram obviamente muito diferentes de hoje. O mundo inteiro se recuperava da destrui\u00e7\u00e3o inimagin\u00e1vel causada pela Segunda Guerra Mundial. Muitas cidades ainda tinham \u00e1reas em ru\u00ednas e infraestrutura b\u00e1sica como estradas, pontes e f\u00e1bricas em toda a Europa permaneciam severamente danificadas e interrompidas. Milh\u00f5es de pessoas foram deslocadas e havia significativa instabilidade econ\u00f4mica e pol\u00edtica. A perspectiva mundial parecia incerta. 1949 viu especificamente a forma\u00e7\u00e3o da Organiza\u00e7\u00e3o do Tratado do Atl\u00e2ntico Norte (OTAN) em abril, o levantamento do bloqueio de Berlim (maio), a R\u00fassia testando sua primeira bomba at\u00f4mica (agosto) e Mao Zedong proclamando o estabelecimento da Rep\u00fablica Popular da China (outubro). Um mundo em fluxo significativo.&nbsp;<\/p>\n\n\n\n<p>Neste contexto, em 1949&nbsp;<a href=\"https:\/\/www.aiglon.ch\/about\/founder-history\">Jo\u00e3o Corlette<\/a>&nbsp;criou nossa escola, uma escola que valoriza o desenvolvimento do car\u00e1ter, a flexibilidade e incentiva a criatividade. Em um mundo de grande incerteza, ele acreditava que, para a educa\u00e7\u00e3o ter valor e impacto, precisava ser hol\u00edstica, baseada em experi\u00eancias e projetada para &quot;preparar os alunos para o amanh\u00e3 e para um mundo em constante movimento&quot;.&nbsp;<\/p>\n\n\n\n<p>Avan\u00e7ando 76 anos, e embora estat\u00edsticas como as citadas por Pinker (2011) sugiram que a humanidade vive uma era de paz e prosperidade sem precedentes, a natureza da &quot;mudan\u00e7a constante&quot; evoluiu. Hoje, \u00e9 a tecnologia, com mudan\u00e7as exponenciais em intelig\u00eancia artificial (IA), Internet das Coisas (IoT), computa\u00e7\u00e3o qu\u00e2ntica, IA incorporada e Interfaces C\u00e9rebro-Computador (ICC), que est\u00e1 mais uma vez criando um futuro imposs\u00edvel de prever. O que parece certo \u00e9 que a mudan\u00e7a ocorrer\u00e1 em velocidades sem precedentes, \u00e0 medida que a humanidade alavanca essas novas tecnologias em benef\u00edcio individual, empresarial e nacional.&nbsp;<\/p>\n\n\n\n<p>Ent\u00e3o, como estamos preparando os alunos da Aiglon 76 anos depois, para um futuro que \u00e9 imposs\u00edvel prever completamente?<\/p>\n\n\n\n<p>A resposta de Aiglon n\u00e3o est\u00e1 em prever o futuro, mas em cultivar a mentalidade, as habilidades e o car\u00e1ter que permitem aos alunos prosperar, independentemente do que o futuro reserva.&nbsp;<\/p>\n\n\n\n<p><strong>&#039;Mente, Corpo, Esp\u00edrito&#039; como base para uma vida que vale a pena ser vivida<\/strong><\/p>\n\n\n\n<p>H\u00e1 alguns anos, a escola sintetizou a vis\u00e3o de John Corlette neste lema simples, mas poderoso, &quot;Mente, Corpo, Esp\u00edrito&quot;. Gostaria de acreditar que John Corlette teria aprovado, pois ele resume o que fazemos como escola todos os dias, em todas as \u00e1reas.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mente<\/strong>: Aprender na Aiglon n\u00e3o se trata de aprender para a prova ou com o livro did\u00e1tico, mas sim de despertar a curiosidade dos alunos, estimulando seu pensamento cr\u00edtico e a resolu\u00e7\u00e3o de problemas. Todos podem ser criativos e ter suas pr\u00f3prias ideias originais, se forem capacitados e incentivados a pensar e compartilhar suas ideias abertamente. O foco de toda a nossa escola em promover a orat\u00f3ria deu a todos voz e direito iguais de serem ouvidos em sala de aula. Em um futuro com intelig\u00eancia artificial (IA), a capacidade de ouvir, refletir, fazer as perguntas certas, analisar informa\u00e7\u00f5es criticamente e inovar ser\u00e1 fundamental.<\/li>\n\n\n\n<li><strong>Corpo<\/strong>O programa Aiglons incentiva todos os alunos a desenvolver resili\u00eancia f\u00edsica, trabalho em equipe e a superar limites pessoais por meio de expedi\u00e7\u00f5es ao ar livre, esportes e esqui. Os alunos aprendem muito fora da sala de aula, desenvolvendo resist\u00eancia, perseveran\u00e7a, autoconfian\u00e7a e a capacidade de lidar com o desconforto e superar desafios aparentemente intranspon\u00edveis. Embora os alunos frequentemente vejam o tempo na montanha como um desenvolvimento de habilidades f\u00edsicas, na realidade eles est\u00e3o desenvolvendo resist\u00eancia mental ou garra e uma mentalidade de crescimento crucial para superar a incerteza no futuro.&nbsp;<\/li>\n\n\n\n<li><strong>Esp\u00edrito:<\/strong>&nbsp;O desenvolvimento do car\u00e1ter, o racioc\u00ednio \u00e9tico, o senso de responsabilidade e o servi\u00e7o s\u00e3o igualmente importantes na Aiglon. Cada novo ano letivo come\u00e7a com uma mensagem de abertura do Diretor da Escola sobre a necessidade de gentileza em todas as coisas. N\u00e3o s\u00e3o apenas palavras. A Aiglon visa desenvolver em cada aluno uma b\u00fassola moral, integridade, compaix\u00e3o e um compromisso com o servi\u00e7o. Em um mundo de incertezas, isso ajudar\u00e1 a guiar os alunos a escolher o caminho certo.<\/li>\n<\/ul>\n\n\n\n<p><strong>Adotando a aprendizagem experiencial<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Al\u00e9m da sala de aula<\/strong>: A Aiglon n\u00e3o limita o aprendizado \u00e0 sala de aula. A aprendizagem experiencial por meio de expedi\u00e7\u00f5es como o Acampamento Espacial da NASA, a navega\u00e7\u00e3o pelas ilhas gregas e as viagens de servi\u00e7o ao Marrocos\/Costa Rica, aplica diretamente o conhecimento da sala de aula a situa\u00e7\u00f5es do mundo real, desenvolvendo habilidades, adaptabilidade e autodescoberta. Viagens de servi\u00e7o, atividades, longas expedi\u00e7\u00f5es culturais e muitas outras experi\u00eancias dispon\u00edveis aos alunos ajudam a dar vida ao aprendizado.&nbsp;<\/li>\n\n\n\n<li><strong>Abordagem multidisciplinar<\/strong>:A escola prim\u00e1ria &#039;<a href=\"https:\/\/online.fliphtml5.com\/meksu\/iazj\/#p=25\">Anos maravilhosos<\/a>&quot;enfrentar desafios do mundo real, combinando hist\u00f3ria, geografia, tecnologia e meio ambiente. Todos os alunos do 9\u00ba ano da Aiglon, por meio do programa<a href=\"https:\/\/www.aiglon.ch\/community\/news\/news\/~board\/public-news\/post\/how-a-new-entrepreneurship-course-is-helping-aiglon-students-shine\">Fus\u00e3o Empresarial<\/a>&quot;Claro, a oportunidade, ao longo de um ano letivo inteiro, de explorar a possibilidade de abrir um neg\u00f3cio pr\u00f3prio, com o apoio de professores dos departamentos de neg\u00f3cios e tecnologia. Essas oportunidades multidisciplinares refletem os problemas complexos e interconectados que os alunos enfrentar\u00e3o no futuro, que raramente se encaixam perfeitamente em disciplinas isoladas.<\/li>\n\n\n\n<li><strong>Rob\u00f3tica e STEM<\/strong>: Aiglon oferece estrutura&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=_4rRnbhzsX4\">aulas de rob\u00f3tica<\/a>&nbsp;e equipes de competi\u00e7\u00e3o em LEGO e VEX. N\u00e3o se trata apenas de habilidades t\u00e9cnicas como codifica\u00e7\u00e3o, mas tamb\u00e9m de colabora\u00e7\u00e3o, pensamento cr\u00edtico, comunica\u00e7\u00e3o eficaz, trabalho em equipe e desenvolvimento de resili\u00eancia por meio de tentativa e erro. Como os rob\u00f4s nunca funcionam na primeira vez, eles oferecem aos alunos a oportunidade de falhar, consertar, falhar e ter sucesso. Uma experi\u00eancia inestim\u00e1vel para qualquer carreira futura. A partir de agosto de 2025, a Aiglon aumentar\u00e1 ainda mais seu compromisso com a inova\u00e7\u00e3o com a abertura de dois novos espa\u00e7os de ponta: o &#039;Laborat\u00f3rio de Inova\u00e7\u00e3o Aplicada e Rob\u00f3tica&#039; (Laborat\u00f3rio AIR) e o &#039;Laborat\u00f3rio de Tecnologias Emergentes&#039; (Laborat\u00f3rio ET). O laborat\u00f3rio ET, em particular, promete ser uma viagem de descoberta onde os alunos podem experimentar novas ferramentas e metodologias, desde realidade virtual e aumentada at\u00e9 simula\u00e7\u00f5es baseadas em IA. Ele tamb\u00e9m fornecer\u00e1 um lar permanente para nossas crescentes equipes de eSports.<\/li>\n<\/ul>\n\n\n\n<p><strong>Integra\u00e7\u00e3o e Uso de Tecnologia<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Educando Educadores<\/strong>: A Aiglon se concentra em equipar seus professores para compreender e integrar novas ferramentas digitais, como a IA, em sala de aula. Isso significa desenvolvimento profissional cont\u00ednuo, experimenta\u00e7\u00e3o e aprendizado compartilhado entre os funcion\u00e1rios. O novo ano letivo come\u00e7ar\u00e1 com todo o corpo docente e administrativo da Aiglon recebendo treinamento com a Gemini AI. O novo roteiro de TI da Aiglon para 2025-2027 tamb\u00e9m descreve uma nova abordagem para o uso de dados e IA em toda a faculdade.<\/li>\n\n\n\n<li><strong>Pol\u00edtica de &quot;Encontre, P\u00e9s, Coma&quot;:<\/strong>&nbsp;Em vez de proibi\u00e7\u00f5es generalizadas, a abordagem da Aiglon para o uso de celulares e dispositivos enfatiza a autorregula\u00e7\u00e3o, a responsabilidade e o uso intencional da tecnologia. Os alunos aprendem quando \u00e9 apropriado usar dispositivos e quando se desconectar, uma habilidade vital para gerenciar distra\u00e7\u00f5es digitais na vida.<a href=\"https:\/\/www.aiglon.ch\/community\/news\/news\/~board\/public-news\/post\/meet-eat-feet-one-year-on#:~:text=Rather%20than%20banning%20mobile%20phones,integral%20part%20of%20modern%20education.\">&nbsp;pol\u00edtica&nbsp;<\/a>destaca que a tecnologia \u00e9 uma ferramenta a ser dominada e temos o dever de ajudar os alunos a se prepararem totalmente &quot;para o amanh\u00e3 e um mundo em constante movimento&quot;.<\/li>\n\n\n\n<li><strong>IA e Tecnologias Emergentes<\/strong>: A Aiglon est\u00e1 adotando a IA e outras tecnologias emergentes para preparar os alunos para um mundo em constante mudan\u00e7a. O Roteiro de TI da escola para 2025-2027 concentra-se em capacitar os alunos e funcion\u00e1rios da Aiglon a usar tecnologia e IA para simplificar processos, remover barreiras e promover a inova\u00e7\u00e3o. Ferramentas de aprendizagem baseadas em IA ser\u00e3o cada vez mais integradas ao cotidiano &quot;daquilo que fazemos&quot;. Ao longo do pr\u00f3ximo ano, desenvolveremos tutores e assistentes digitais personalizados para alunos do ensino m\u00e9dio, oferecendo experi\u00eancias de aprendizagem personalizadas, feedback instant\u00e2neo e caminhos de estudo guiados que se adaptam \u00e0s suas necessidades. A abordagem da escola para IA \u00e9 centrada no ser humano, com o objetivo de aprimorar a autonomia do aluno e o acesso \u00e0 aprendizagem; isso n\u00e3o substituir\u00e1 o papel dos professores.&nbsp;<\/li>\n\n\n\n<li><strong>Reimaginando a Avalia\u00e7\u00e3o<\/strong>: \u00c0 medida que o nosso mundo muda rapidamente, a Aiglon e a educa\u00e7\u00e3o como ind\u00fastria precisar\u00e3o reformular sua abordagem \u00e0 avalia\u00e7\u00e3o. \u00c0 medida que o cen\u00e1rio educacional continua a evoluir, a Aiglon est\u00e1 ativamente explorando e reinventando metodologias de avalia\u00e7\u00e3o, garantindo que nossos alunos e professores n\u00e3o sejam apenas reativos, mas tamb\u00e9m preparados para liderar e ter sucesso em quaisquer novos paradigmas que surjam.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>A abordagem da Aiglon n\u00e3o \u00e9 sobre saber o que o futuro reserva, mas sobre equipar nossos incr\u00edveis alunos com a adaptabilidade, integridade e curiosidade intelectual para mold\u00e1-lo com confian\u00e7a, assim como John Corlette pretendia preparar os alunos para sua pr\u00f3pria era de incerteza.&nbsp;<\/p>\n\n\n\n<p>Se voc\u00ea quiser informa\u00e7\u00f5es adicionais sobre Tecnologia no Aiglon College, entre em contato.&nbsp;<\/p>\n\n\n\n<p>Darren Wise, Diretor de Tecnologia e Estrat\u00e9gia Digital&nbsp;<a href=\"https:\/\/www.las.ch\/about\/news-events\/las-blog\/~board\/las-blogs\/post\/student-learning-and-growth-found-in-travel\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>When John Corlette founded Aiglon College in 1949, things were obviously very different to today. The whole world was recovering from the unimaginable destruction caused by World War II. Many cities had areas still in ruins and basic infrastructure like roads, bridges, factories across Europe remained severely damaged and disrupted. Millions of people had been [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12852,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[],"class_list":["post-12851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preparing Students for Tomorrow, and a World in Constant Change<\/title>\n<meta name=\"description\" content=\"Preparing Students for Tomorrow, and a World in Constant Change\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.swisslearning.com\/pt\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preparing Students for Tomorrow, and a World in Constant Change\" \/>\n<meta property=\"og:description\" content=\"Preparing Students for Tomorrow, and a World in Constant Change\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.swisslearning.com\/pt\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Learning\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swisslearning\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-18T05:56:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T05:59:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-18-at-13.54.42-1024x646.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Isabelle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabelle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/\"},\"author\":{\"name\":\"Isabelle\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"headline\":\"Preparing Students for Tomorrow, and a World in Constant Change\",\"datePublished\":\"2025-08-18T05:56:03+00:00\",\"dateModified\":\"2025-08-18T05:59:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/\"},\"wordCount\":1309,\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Screenshot-2025-08-18-at-13.54.42.png\",\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/\",\"name\":\"Preparing Students for Tomorrow, and a World in Constant Change\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Screenshot-2025-08-18-at-13.54.42.png\",\"datePublished\":\"2025-08-18T05:56:03+00:00\",\"dateModified\":\"2025-08-18T05:59:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\"},\"description\":\"Preparing Students for Tomorrow, and a World in Constant Change\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Screenshot-2025-08-18-at-13.54.42.png\",\"contentUrl\":\"https:\\\/\\\/www.swisslearning.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Screenshot-2025-08-18-at-13.54.42.png\",\"width\":1598,\"height\":1008},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/news\\\/preparing-students-for-tomorrow-and-a-world-in-constant-change\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.swisslearning.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preparing Students for Tomorrow, and a World in Constant Change\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#website\",\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/\",\"name\":\"Swiss Learning\",\"description\":\"BOARDING SCHOOLS, HOTEL MANAGEMENT SCHOOLS AND CAMPS IN SWITZERLAND\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.swisslearning.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.swisslearning.com\\\/#\\\/schema\\\/person\\\/512a780e070f7061a72b72aa9cdcc844\",\"name\":\"Isabelle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g\",\"caption\":\"Isabelle\"},\"url\":\"https:\\\/\\\/www.swisslearning.com\\\/pt\\\/author\\\/isabelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preparando os alunos para o amanh\u00e3 e um mundo em constante mudan\u00e7a","description":"Preparando os alunos para o amanh\u00e3 e um mundo em constante mudan\u00e7a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.swisslearning.com\/pt\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/","og_locale":"pt_BR","og_type":"article","og_title":"Preparing Students for Tomorrow, and a World in Constant Change","og_description":"Preparing Students for Tomorrow, and a World in Constant Change","og_url":"https:\/\/www.swisslearning.com\/pt\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/","og_site_name":"Swiss Learning","article_publisher":"https:\/\/www.facebook.com\/swisslearning","article_published_time":"2025-08-18T05:56:03+00:00","article_modified_time":"2025-08-18T05:59:01+00:00","og_image":[{"width":1024,"height":646,"url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-18-at-13.54.42-1024x646.png","type":"image\/png"}],"author":"Isabelle","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Isabelle","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/#article","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/"},"author":{"name":"Isabelle","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"headline":"Preparing Students for Tomorrow, and a World in Constant Change","datePublished":"2025-08-18T05:56:03+00:00","dateModified":"2025-08-18T05:59:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/"},"wordCount":1309,"image":{"@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-18-at-13.54.42.png","articleSection":["News"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/","url":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/","name":"Preparando os alunos para o amanh\u00e3 e um mundo em constante mudan\u00e7a","isPartOf":{"@id":"https:\/\/www.swisslearning.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/#primaryimage"},"image":{"@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/#primaryimage"},"thumbnailUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-18-at-13.54.42.png","datePublished":"2025-08-18T05:56:03+00:00","dateModified":"2025-08-18T05:59:01+00:00","author":{"@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844"},"description":"Preparando os alunos para o amanh\u00e3 e um mundo em constante mudan\u00e7a","breadcrumb":{"@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/#primaryimage","url":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-18-at-13.54.42.png","contentUrl":"https:\/\/www.swisslearning.com\/wp-content\/uploads\/2025\/08\/Screenshot-2025-08-18-at-13.54.42.png","width":1598,"height":1008},{"@type":"BreadcrumbList","@id":"https:\/\/www.swisslearning.com\/news\/preparing-students-for-tomorrow-and-a-world-in-constant-change\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.swisslearning.com\/"},{"@type":"ListItem","position":2,"name":"Preparing Students for Tomorrow, and a World in Constant Change"}]},{"@type":"WebSite","@id":"https:\/\/www.swisslearning.com\/#website","url":"https:\/\/www.swisslearning.com\/","name":"Swiss Learning","description":"ESCOLAS DE EMBARQUE, ESCOLAS DE GEST\u00c3O DE HOTELARIA E CAMPS NA SU\u00cd\u00c7A","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.swisslearning.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.swisslearning.com\/#\/schema\/person\/512a780e070f7061a72b72aa9cdcc844","name":"Isabelle","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fe546a12218bf41a42b91135de2222e01f5b175bea26679715cc0130484df73f?s=96&d=mm&r=g","caption":"Isabelle"},"url":"https:\/\/www.swisslearning.com\/pt\/author\/isabelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts\/12851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/comments?post=12851"}],"version-history":[{"count":3,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts\/12851\/revisions"}],"predecessor-version":[{"id":12855,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/posts\/12851\/revisions\/12855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/media\/12852"}],"wp:attachment":[{"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/media?parent=12851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/categories?post=12851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.swisslearning.com\/pt\/wp-json\/wp\/v2\/tags?post=12851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}